{"id":99,"count":1,"description":"","link":"https:\/\/asmaatravel.com\/blog\/tag\/what-is-a-riad\/","name":"What is a Riad?","slug":"what-is-a-riad","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/asmaatravel.com\/blog\/wp-json\/wp\/v2\/tags\/99","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asmaatravel.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/asmaatravel.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/asmaatravel.com\/blog\/wp-json\/wp\/v2\/posts?tags=99"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}